{"id":2106,"date":"2023-05-20T07:38:02","date_gmt":"2023-05-20T07:38:02","guid":{"rendered":"https:\/\/almenrausch-berglern.de\/WordPress_02\/?post_type=presseartikel&#038;p=2106"},"modified":"2023-05-20T07:38:02","modified_gmt":"2023-05-20T07:38:02","slug":"bericht-erdinger-anzeiger-vom-20-05-2023-1-mai-2023","status":"publish","type":"presseartikel","link":"https:\/\/almenrausch-berglern.de\/WordPress_02\/presseartikel\/bericht-erdinger-anzeiger-vom-20052023-1-mai-2023\/","title":{"rendered":"Bericht Erdinger Anzeiger vom 20.05.2023 &#8211; 1. Mai 2023"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2107\" src=\"https:\/\/almenrausch-berglern.de\/WordPress_02\/wp-content\/uploads\/2023\/05\/bericht_alb_ea_20230520.jpg\" alt=\"\" width=\"1645\" height=\"939\" srcset=\"https:\/\/almenrausch-berglern.de\/WordPress_02\/wp-content\/uploads\/2023\/05\/bericht_alb_ea_20230520.jpg 1645w, https:\/\/almenrausch-berglern.de\/WordPress_02\/wp-content\/uploads\/2023\/05\/bericht_alb_ea_20230520-300x171.jpg 300w, https:\/\/almenrausch-berglern.de\/WordPress_02\/wp-content\/uploads\/2023\/05\/bericht_alb_ea_20230520-1024x585.jpg 1024w, https:\/\/almenrausch-berglern.de\/WordPress_02\/wp-content\/uploads\/2023\/05\/bericht_alb_ea_20230520-768x438.jpg 768w, https:\/\/almenrausch-berglern.de\/WordPress_02\/wp-content\/uploads\/2023\/05\/bericht_alb_ea_20230520-1536x877.jpg 1536w\" sizes=\"auto, (max-width: 1645px) 100vw, 1645px\" \/><\/p>\n","protected":false},"template":"","meta":{"ngg_post_thumbnail":0},"class_list":["post-2106","presseartikel","type-presseartikel","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bericht Erdinger Anzeiger vom 20.05.2023 - 1. Mai 2023 - SG Almenrausch Berglern e.V.<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bericht Erdinger Anzeiger vom 20.05.2023 - 1. Mai 2023 - SG Almenrausch Berglern e.V.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/almenrausch-berglern.de\/WordPress_02\/presseartikel\/bericht-erdinger-anzeiger-vom-20052023-1-mai-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"SG Almenrausch Berglern e.V.\" \/>\n<meta property=\"og:image\" content=\"https:\/\/almenrausch-berglern.de\/WordPress_02\/wp-content\/uploads\/2023\/05\/bericht_alb_ea_20230520.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/almenrausch-berglern.de\/WordPress_02\/presseartikel\/bericht-erdinger-anzeiger-vom-20052023-1-mai-2023\/\",\"url\":\"https:\/\/almenrausch-berglern.de\/WordPress_02\/presseartikel\/bericht-erdinger-anzeiger-vom-20052023-1-mai-2023\/\",\"name\":\"Bericht Erdinger Anzeiger vom 20.05.2023 - 1. Mai 2023 - SG Almenrausch Berglern e.V.\",\"isPartOf\":{\"@id\":\"https:\/\/almenrausch-berglern.de\/WordPress_02\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/almenrausch-berglern.de\/WordPress_02\/presseartikel\/bericht-erdinger-anzeiger-vom-20052023-1-mai-2023\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/almenrausch-berglern.de\/WordPress_02\/presseartikel\/bericht-erdinger-anzeiger-vom-20052023-1-mai-2023\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/almenrausch-berglern.de\/WordPress_02\/wp-content\/uploads\/2023\/05\/bericht_alb_ea_20230520.jpg\",\"datePublished\":\"2023-05-20T07:38:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/almenrausch-berglern.de\/WordPress_02\/presseartikel\/bericht-erdinger-anzeiger-vom-20052023-1-mai-2023\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/almenrausch-berglern.de\/WordPress_02\/presseartikel\/bericht-erdinger-anzeiger-vom-20052023-1-mai-2023\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/almenrausch-berglern.de\/WordPress_02\/presseartikel\/bericht-erdinger-anzeiger-vom-20052023-1-mai-2023\/#primaryimage\",\"url\":\"https:\/\/almenrausch-berglern.de\/WordPress_02\/wp-content\/uploads\/2023\/05\/bericht_alb_ea_20230520.jpg\",\"contentUrl\":\"https:\/\/almenrausch-berglern.de\/WordPress_02\/wp-content\/uploads\/2023\/05\/bericht_alb_ea_20230520.jpg\",\"width\":1645,\"height\":939},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/almenrausch-berglern.de\/WordPress_02\/presseartikel\/bericht-erdinger-anzeiger-vom-20052023-1-mai-2023\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/almenrausch-berglern.de\/WordPress_02\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Presseartikel\",\"item\":\"https:\/\/almenrausch-berglern.de\/WordPress_02\/presseartikel\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bericht Erdinger Anzeiger vom 20.05.2023 &#8211; 1. Mai 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/almenrausch-berglern.de\/WordPress_02\/#website\",\"url\":\"https:\/\/almenrausch-berglern.de\/WordPress_02\/\",\"name\":\"SG Almenrausch Berglern e.V.\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/almenrausch-berglern.de\/WordPress_02\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bericht Erdinger Anzeiger vom 20.05.2023 - 1. Mai 2023 - SG Almenrausch Berglern e.V.","robots":{"index":"noindex","follow":"follow"},"og_locale":"de_DE","og_type":"article","og_title":"Bericht Erdinger Anzeiger vom 20.05.2023 - 1. Mai 2023 - SG Almenrausch Berglern e.V.","og_url":"https:\/\/almenrausch-berglern.de\/WordPress_02\/presseartikel\/bericht-erdinger-anzeiger-vom-20052023-1-mai-2023\/","og_site_name":"SG Almenrausch Berglern e.V.","og_image":[{"url":"https:\/\/almenrausch-berglern.de\/WordPress_02\/wp-content\/uploads\/2023\/05\/bericht_alb_ea_20230520.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/almenrausch-berglern.de\/WordPress_02\/presseartikel\/bericht-erdinger-anzeiger-vom-20052023-1-mai-2023\/","url":"https:\/\/almenrausch-berglern.de\/WordPress_02\/presseartikel\/bericht-erdinger-anzeiger-vom-20052023-1-mai-2023\/","name":"Bericht Erdinger Anzeiger vom 20.05.2023 - 1. Mai 2023 - SG Almenrausch Berglern e.V.","isPartOf":{"@id":"https:\/\/almenrausch-berglern.de\/WordPress_02\/#website"},"primaryImageOfPage":{"@id":"https:\/\/almenrausch-berglern.de\/WordPress_02\/presseartikel\/bericht-erdinger-anzeiger-vom-20052023-1-mai-2023\/#primaryimage"},"image":{"@id":"https:\/\/almenrausch-berglern.de\/WordPress_02\/presseartikel\/bericht-erdinger-anzeiger-vom-20052023-1-mai-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/almenrausch-berglern.de\/WordPress_02\/wp-content\/uploads\/2023\/05\/bericht_alb_ea_20230520.jpg","datePublished":"2023-05-20T07:38:02+00:00","breadcrumb":{"@id":"https:\/\/almenrausch-berglern.de\/WordPress_02\/presseartikel\/bericht-erdinger-anzeiger-vom-20052023-1-mai-2023\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/almenrausch-berglern.de\/WordPress_02\/presseartikel\/bericht-erdinger-anzeiger-vom-20052023-1-mai-2023\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/almenrausch-berglern.de\/WordPress_02\/presseartikel\/bericht-erdinger-anzeiger-vom-20052023-1-mai-2023\/#primaryimage","url":"https:\/\/almenrausch-berglern.de\/WordPress_02\/wp-content\/uploads\/2023\/05\/bericht_alb_ea_20230520.jpg","contentUrl":"https:\/\/almenrausch-berglern.de\/WordPress_02\/wp-content\/uploads\/2023\/05\/bericht_alb_ea_20230520.jpg","width":1645,"height":939},{"@type":"BreadcrumbList","@id":"https:\/\/almenrausch-berglern.de\/WordPress_02\/presseartikel\/bericht-erdinger-anzeiger-vom-20052023-1-mai-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/almenrausch-berglern.de\/WordPress_02\/"},{"@type":"ListItem","position":2,"name":"Presseartikel","item":"https:\/\/almenrausch-berglern.de\/WordPress_02\/presseartikel\/"},{"@type":"ListItem","position":3,"name":"Bericht Erdinger Anzeiger vom 20.05.2023 &#8211; 1. Mai 2023"}]},{"@type":"WebSite","@id":"https:\/\/almenrausch-berglern.de\/WordPress_02\/#website","url":"https:\/\/almenrausch-berglern.de\/WordPress_02\/","name":"SG Almenrausch Berglern e.V.","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/almenrausch-berglern.de\/WordPress_02\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-05-20 21:24:36","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/almenrausch-berglern.de\/WordPress_02\/wp-json\/wp\/v2\/presseartikel\/2106","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/almenrausch-berglern.de\/WordPress_02\/wp-json\/wp\/v2\/presseartikel"}],"about":[{"href":"https:\/\/almenrausch-berglern.de\/WordPress_02\/wp-json\/wp\/v2\/types\/presseartikel"}],"wp:attachment":[{"href":"https:\/\/almenrausch-berglern.de\/WordPress_02\/wp-json\/wp\/v2\/media?parent=2106"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}